{"id":28694,"date":"2026-09-02T05:18:06","date_gmt":"2026-09-02T05:18:06","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/trophy-2026-hoevelhof\/"},"modified":"2026-09-02T05:18:06","modified_gmt":"2026-09-02T05:18:06","slug":"trophy-2026-hoevelhof","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/en\/padel-tournaments-2\/trophy-2026-hoevelhof\/","title":{"rendered":"Trophy 2026 &#8211; H\u00f6velhof"},"content":{"rendered":"<p>Der H\u00f6velhofer TC Blau Wei\u00df e.V. in H\u00f6velhof l\u00e4dt zur <strong>Trophy 2026 \u2013 H\u00f6velhof<\/strong> ein. Das Turnier findet am <strong>3. Oktober 2026<\/strong> statt und bietet Padel-Begeisterten die M\u00f6glichkeit, sich in einem sportlichen Wettbewerb zu messen.<\/p>\n<p>Die Anmeldung ist ab sofort \u00fcber das offizielle DPV-Portal m\u00f6glich. Interessierte k\u00f6nnen sich unter folgendem Link registrieren: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/72ef1198-bb8d-4cd6-9a19-64660773e26d\" rel=\"nofollow noopener\" target=\"_blank\">Zur Anmeldung<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der H\u00f6velhofer TC Blau Wei\u00df e.V. in H\u00f6velhof l\u00e4dt zur Trophy 2026 \u2013 H\u00f6velhof ein. Das Turnier findet am 3. Oktober 2026 statt und bietet Padel-Begeisterten die M\u00f6glichkeit, sich in einem sportlichen Wettbewerb zu messen. Die Anmeldung ist ab sofort \u00fcber das offizielle DPV-Portal m\u00f6glich. Interessierte k\u00f6nnen sich unter folgendem Link registrieren: Zur Anmeldung.<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[277],"class_list":["post-28694","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-10-03","single_start_time":"08:00:00","single_end_date":"2026-10-03","single_end_time":"18:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/72ef1198-bb8d-4cd6-9a19-64660773e26d","venue":{"venue_title":"H\u00f6velhofer TC Blau Wei\u00df e.V.","address":"Von-der-Recke-Str. 30, H\u00f6velhof","location":{"address":"Tennisclub Blau-Wei\u00df e.V., 30, Von-der-Recke-Stra\u00dfe, Bentlake, H\u00f6velhof, Kreis Paderborn, Nordrhein-Westfalen, 33161, Deutschland","lat":51.8268424,"lng":8.6618239,"zoom":14,"place_id":140451544,"city":"H\u00f6velhof","state":"Nordrhein-Westfalen","post_code":33161,"country":"DE"},"postal_code":"33161","city":"H\u00f6velhof","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_c975f2a1-eb1a-4ca5-b967-3b07022dfead"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event\/28694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/media?parent=28694"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/tags?post=28694"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event_category?post=28694"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event_level?post=28694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}