{"id":28702,"date":"2026-09-02T05:18:15","date_gmt":"2026-09-02T05:18:15","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/the-smash-lounge-altdorf-2\/"},"modified":"2026-09-02T05:18:15","modified_gmt":"2026-09-02T05:18:15","slug":"the-smash-lounge-altdorf-2","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/en\/padel-tournaments-2\/the-smash-lounge-altdorf-2\/","title":{"rendered":"The Smash Lounge &#8211; Altdorf"},"content":{"rendered":"<p>Am 20. September 2026 findet in der The Smash Lounge in Altdorf das Padel-Turnier <strong>The Smash Lounge &#8211; Altdorf<\/strong> statt. Wer sich f\u00fcr einen spannenden Wettkampftag auf dem Padel-Court begeistert, ist hier genau richtig.<\/p>\n<p>Die Anmeldung zum Turnier ist bequem online m\u00f6glich \u2013 einfach den folgenden Link nutzen und einen der begehrten Startpl\u00e4tze sichern: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/f07068c1-faa4-4c6f-a317-1bd2adfb0200\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 20. September 2026 findet in der The Smash Lounge in Altdorf das Padel-Turnier The Smash Lounge &#8211; Altdorf statt. Wer sich f\u00fcr einen spannenden Wettkampftag auf dem Padel-Court begeistert, ist hier genau richtig. Die Anmeldung zum Turnier ist bequem online m\u00f6glich \u2013 einfach den folgenden Link nutzen und einen der begehrten Startpl\u00e4tze sichern: Jetzt&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277],"class_list":["post-28702","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-09-20","single_start_time":"08:00:00","single_end_date":"2026-09-20","single_end_time":"13:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/f07068c1-faa4-4c6f-a317-1bd2adfb0200","venue":{"venue_title":"The Smash Lounge","address":"Sch\u00f6nbuchstr. 41, Altdorf","location":{"address":"41, Sch\u00f6nbuchstra\u00dfe, Altdorf, GVV Holzgerlingen, Landkreis B\u00f6blingen, Baden-W\u00fcrttemberg, 71155, Deutschland","lat":48.6263943,"lng":9.0012213,"zoom":14,"place_id":122298424,"city":"Altdorf","state":"Baden-W\u00fcrttemberg","post_code":71155,"country":"DE"},"postal_code":"71155","city":"Altdorf","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_1ae01a61-5e4c-4a72-8502-b3e700fcf048"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event\/28702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/media?parent=28702"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/tags?post=28702"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event_category?post=28702"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/en\/wp-json\/wp\/v2\/ecom_event_level?post=28702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}