{"id":28530,"date":"2026-08-29T05:16:57","date_gmt":"2026-08-29T05:16:57","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/sparkasse-lions-summer-circuit-5\/"},"modified":"2026-08-29T05:16:57","modified_gmt":"2026-08-29T05:16:57","slug":"sparkasse-lions-summer-circuit-5","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/es\/torneos-de-padel-2\/sparkasse-lions-summer-circuit-5\/","title":{"rendered":"SPARKASSE Lions Summer Circuit"},"content":{"rendered":"<p>El <strong>SPARKASSE Lions Summer Circuit<\/strong> findet am <strong>1. September 2026<\/strong> in der <strong>Padel Bruck in Bruck an der Mur<\/strong> statt. Das Turnier ist ein weiterer H\u00f6hepunkt im heimischen Padel-Kalender und verspricht spannende Matches in angenehmer Atmosph\u00e4re.<\/p>\n<p>Interessierte Spielerinnen und Spieler k\u00f6nnen sich direkt \u00fcber den offiziellen Anmeldelink registrieren: <a href=\"https:\/\/padel-austria.at\/ranked\/tournaments\/5898c3ae-7076-4eb9-8614-822e89541ed3\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>. Sichert euch euren Startplatz und seid dabei!<\/p>","protected":false},"excerpt":{"rendered":"<p>Der SPARKASSE Lions Summer Circuit findet am 1. September 2026 in der Padel Bruck in Bruck an der Mur statt. Das Turnier ist ein weiterer H\u00f6hepunkt im heimischen Padel-Kalender und verspricht spannende Matches in angenehmer Atmosph\u00e4re. Interessierte Spielerinnen und Spieler k\u00f6nnen sich direkt \u00fcber den offiziellen Anmeldelink registrieren: Jetzt anmelden. Sichert euch euren Startplatz und&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277],"class_list":["post-28530","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-09-01","single_start_time":"17:30:00","single_end_date":"2026-09-01","single_end_time":"21:30:00","geschlecht":[],"event_company":[16551],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/padel-austria.at\/ranked\/tournaments\/5898c3ae-7076-4eb9-8614-822e89541ed3","venue":{"venue_title":"Padel Bruck","address":"Murinsel 11, 8600 Bruck an der Mur","location":{"address":"Murinsel 11, 8600 Bruck an der Mur","lat":47.4036349974516,"lng":15.2449823284665,"zoom":14,"place_id":"","city":"Bruck an der Mur","state":"Steiermark","post_code":8600,"country":"AT"},"postal_code":"8600","city":"Bruck an der Mur","country":"AT","website":"","contact_person":"","email":"","phone":""},"uuid":"at_5898c3ae-7076-4eb9-8614-822e89541ed3"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event\/28530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/padel_association\/16551"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/media?parent=28530"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/tags?post=28530"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_category?post=28530"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_level?post=28530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}