{"id":28692,"date":"2026-09-02T05:18:00","date_gmt":"2026-09-02T05:18:00","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/hall-of-padelbraunschweig\/"},"modified":"2026-09-02T05:18:00","modified_gmt":"2026-09-02T05:18:00","slug":"hall-of-padelbraunschweig","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/es\/torneos-de-padel-2\/hall-of-padelbraunschweig\/","title":{"rendered":"HALL OF PADELBraunschweig"},"content":{"rendered":"<p>Das Turnier <strong>HALL OF PADEL Braunschweig<\/strong> findet am <strong>3. Oktober 2026<\/strong> in der <strong>HALL OF PADEL Braunschweig<\/strong> statt. Padel-Fans und Aktive aus der Region d\u00fcrfen sich auf einen sportlichen Wettkampftag in Braunschweig freuen.<\/p>\n<p>Die Anmeldung ist ab sofort \u00fcber den offiziellen Link m\u00f6glich: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/d772ef1d-4665-4c73-a817-5ebe8148e1a0\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>. Sichert euch euren Startplatz und seid dabei!<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Turnier HALL OF PADEL Braunschweig findet am 3. Oktober 2026 in der HALL OF PADEL Braunschweig statt. Padel-Fans und Aktive aus der Region d\u00fcrfen sich auf einen sportlichen Wettkampftag in Braunschweig freuen. Die Anmeldung ist ab sofort \u00fcber den offiziellen Link m\u00f6glich: Jetzt anmelden. Sichert euch euren Startplatz und seid dabei!<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277],"class_list":["post-28692","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-10-03","single_start_time":"13:00:00","single_end_date":"2026-10-03","single_end_time":"21:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/d772ef1d-4665-4c73-a817-5ebe8148e1a0","venue":{"venue_title":"HALL OF PADEL Braunschweig","address":"Hamburger Stra\u00dfe 52, Braunschweig","location":{"address":"52, Hamburger Stra\u00dfe, Schwarzer Berg, Nordstadt-Schunteraue, Braunschweig, Niedersachsen, 38114, Deutschland","lat":52.2830223,"lng":10.517912,"zoom":14,"place_id":144124485,"city":"Braunschweig","state":"Niedersachsen","post_code":38114,"country":"DE"},"postal_code":"38114","city":"Braunschweig","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_49e1f0f6-458d-4d96-8ad3-84fca382cc10"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event\/28692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/media?parent=28692"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/tags?post=28692"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_category?post=28692"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_level?post=28692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}