{"id":28696,"date":"2026-09-02T05:18:09","date_gmt":"2026-09-02T05:18:09","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/padel-planet-bei-magdeburg-27\/"},"modified":"2026-09-02T05:18:09","modified_gmt":"2026-09-02T05:18:09","slug":"padel-planet-bei-magdeburg-27","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/es\/torneos-de-padel-2\/padel-planet-bei-magdeburg-27\/","title":{"rendered":"Padel Planet (bei Magdeburg)"},"content":{"rendered":"<p>Am 3. Oktober 2026 findet im Padel Planet GmbH in Sch\u00f6nebeck (Elbe), in der N\u00e4he von Magdeburg, das Turnier <strong>Padel Planet (bei Magdeburg)<\/strong> statt. Ein attraktiver Termin am Feiertag f\u00fcr alle Padel-Begeisterten der Region.<\/p>\n<p>Die Anmeldung ist ab sofort \u00fcber den offiziellen DPV-Portal-Link m\u00f6glich: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/52ebcc0e-9d03-4e35-8067-bd00d0493988\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>. Sichert euch euren Startplatz und seid dabei!<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 3. Oktober 2026 findet im Padel Planet GmbH in Sch\u00f6nebeck (Elbe), in der N\u00e4he von Magdeburg, das Turnier Padel Planet (bei Magdeburg) statt. Ein attraktiver Termin am Feiertag f\u00fcr alle Padel-Begeisterten der Region. Die Anmeldung ist ab sofort \u00fcber den offiziellen DPV-Portal-Link m\u00f6glich: Jetzt anmelden. Sichert euch euren Startplatz und seid dabei!<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277],"class_list":["post-28696","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-10-03","single_start_time":"08:00:00","single_end_date":"2026-10-03","single_end_time":"14:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/52ebcc0e-9d03-4e35-8067-bd00d0493988","venue":{"venue_title":"Padel Planet GmbH","address":"Stadionstr. 19, Sch\u00f6nebeck","location":{"address":"Sportcenter, 19, Stadionstra\u00dfe, Sch\u00f6nebeck-Salzelmen, Gr\u00fcnewalde, Sch\u00f6nebeck (Elbe), Salzlandkreis, Sachsen-Anhalt, 39218, Deutschland","lat":52.0135236,"lng":11.7182817,"zoom":14,"place_id":145196765,"city":"Sch\u00f6nebeck (Elbe)","state":"Sachsen-Anhalt","post_code":39218,"country":"DE"},"postal_code":"39218","city":"Sch\u00f6nebeck (Elbe)","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_83ef8d0d-e3a4-4bc6-917e-af3d05af9841"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event\/28696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/media?parent=28696"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/tags?post=28696"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_category?post=28696"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/es\/wp-json\/wp\/v2\/ecom_event_level?post=28696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}