{"id":25433,"date":"2026-03-14T03:06:00","date_gmt":"2026-03-14T03:06:00","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-50-herren-early-bird-padelon-muelheim\/"},"modified":"2026-03-27T03:05:55","modified_gmt":"2026-03-27T03:05:55","slug":"dpv-gps-50-herren-early-bird-padelon-muelheim","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/fr\/tournois-de-padel-2\/dpv-gps-50-herren-early-bird-padelon-muelheim\/","title":{"rendered":"GPS 50 Herren &#8211; [EARLY BIRD] &#8211; Padelon M\u00fclheim"},"content":{"rendered":"<p>Das Paddelturnier &#8222;GPS 50 Herren &#8211; EARLY BIRD&#8220; findet bei Padelon M\u00fclheim in M\u00fclheim an der Ruhr statt. Es werden bis zu acht Teams antreten, wobei der Austragungsmodus im K.O.-System mit einer Nebenrunde vorgesehen ist, sodass jedes Team mindestens zwei Matches absolvieren kann. Die Teilnahmegeb\u00fchr betr\u00e4gt 40 Euro pro Person und kann am Veranstaltungstag per PayPal oder EC-Cash bezahlt werden. Der Veranstalter Padelon M\u00fclheim k\u00fcmmert sich engagiert um das Event. Als Preise winken Sachpreise, die dank der Unterst\u00fctzung von Partnern zur Verf\u00fcgung stehen. Das Turnier dient als gute Gelegenheit f\u00fcr Spieler, erste nationale Punkte im DPV Ranking zu sammeln und Erfahrungen zu erweitern. Teilnehmer m\u00fcssen keine DPV-Lizenz besitzen, um mitzumachen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Paddelturnier &#8222;GPS 50 Herren &#8211; EARLY BIRD&#8220; findet bei Padelon M\u00fclheim in M\u00fclheim an der Ruhr statt. Es werden bis zu acht Teams antreten, wobei der Austragungsmodus im K.O.-System mit einer Nebenrunde vorgesehen ist, sodass jedes Team mindestens zwei Matches absolvieren kann. Die Teilnahmegeb\u00fchr betr\u00e4gt 40 Euro pro Person und kann am Veranstaltungstag per&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[284],"class_list":["post-25433","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-weltklasse"],"acf":{"cpt_status":"inactive","type":"event","single_start_date":"20260326","single_start_time":"10:00:00","single_end_date":"20260326","single_end_time":"13:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":40,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/65908","venue":{"venue_title":"Padelon M\u00fclheim","address":"Nikolaus-Ehlen-Stra\u00dfe 18, 45475 M\u00fclheim an der Ruhr, Germany","location":{"address":"Nikolaus-Ehlen-Stra\u00dfe 18, 45475 M\u00fclheim an der Ruhr, Deutschland","lat":51.4570799,"lng":6.894872599999999,"zoom":14,"city":"M\u00fclheim an der Ruhr","country":"DE","country_short":"DE","post_code":45475},"postal_code":"45475","city":"M\u00fclheim an der Ruhr","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_65908"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event\/25433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/media?parent=25433"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/tags?post=25433"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event_category?post=25433"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event_level?post=25433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}