{"id":25436,"date":"2026-03-14T03:06:08","date_gmt":"2026-03-14T03:06:08","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-50-herren-early-bird-by-padelbox-koeln-weiden\/"},"modified":"2026-03-28T03:06:26","modified_gmt":"2026-03-28T03:06:26","slug":"dpv-gps-50-herren-early-bird-by-padelbox-koeln-weiden","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/fr\/tournois-de-padel-2\/dpv-gps-50-herren-early-bird-by-padelbox-koeln-weiden\/","title":{"rendered":"GPS 50 Herren &#8211; Early Bird &#8211; by padelBOX K\u00f6ln-Weiden"},"content":{"rendered":"<p>Das Paddelturnier \u201eGPS 50 Herren &#8211; Early Bird\u201c findet in der \u201epadelBOX K\u00f6ln-Weiden\u201c statt. Insgesamt nehmen 20 Spieler teil, die sich in maximal 8 Teams aufteilen. Der Veranstalter, die padelBOX K\u00f6ln-Weiden, stellt sicher, dass das Turnier in einem K.O.-System mit Nebenrunde gespielt wird, sodass jedes Team garantiert zwei Matches hat. Eine Teilnahmegeb\u00fchr von 35 Euro pro Person ist erforderlich, die direkt bei der Anmeldung \u00fcber den Anbieter Stripe zu begleichen ist. Das Event startet am 27. M\u00e4rz 2026 um 09:00 Uhr und endet gegen 13:00 Uhr.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Paddelturnier \u201eGPS 50 Herren &#8211; Early Bird\u201c findet in der \u201epadelBOX K\u00f6ln-Weiden\u201c statt. Insgesamt nehmen 20 Spieler teil, die sich in maximal 8 Teams aufteilen. Der Veranstalter, die padelBOX K\u00f6ln-Weiden, stellt sicher, dass das Turnier in einem K.O.-System mit Nebenrunde gespielt wird, sodass jedes Team garantiert zwei Matches hat. Eine Teilnahmegeb\u00fchr von 35 Euro&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[277],"class_list":["post-25436","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"inactive","type":"event","single_start_date":"20260327","single_start_time":"09:00:00","single_end_date":"20260327","single_end_time":"13:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":35,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/62583","venue":{"venue_title":"padelBOX K\u00f6ln-Weiden","address":"Kronst\u00e4dter Str. 100, 50858 K\u00f6ln, Germany","location":{"address":"Kronst\u00e4dter Str. 100, 50858 K\u00f6ln-Lindenthal, Deutschland","lat":50.9282644,"lng":6.840993099999999,"zoom":14,"city":"K\u00f6ln","country":"DE","country_short":"DE","post_code":50858},"postal_code":"50858","city":"K\u00f6ln","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_62583"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event\/25436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/media?parent=25436"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/tags?post=25436"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event_category?post=25436"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/fr\/wp-json\/wp\/v2\/ecom_event_level?post=25436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}