{"id":28547,"date":"2026-08-29T05:17:57","date_gmt":"2026-08-29T05:17:57","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/padeldome-breakfast-club-das-original-%f0%9f%a5%90%e2%98%95-%f0%9f%8d%ad-10\/"},"modified":"2026-08-29T05:17:57","modified_gmt":"2026-08-29T05:17:57","slug":"padeldome-breakfast-club-das-original-%f0%9f%a5%90%e2%98%95-%f0%9f%8d%ad-10","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/it\/tornei-di-padel-2\/padeldome-breakfast-club-das-original-%f0%9f%a5%90%e2%98%95-%f0%9f%8d%ad-10\/","title":{"rendered":"Padeldome Breakfast Club &#8211; das ORIGINAL \ud83e\udd50\u2615 \ud83c\udf6d"},"content":{"rendered":"<p>Am 1. September 2026 findet im PADELDOME Erdberg in Wien (U3 Erdberg) der <strong>Padeldome Breakfast Club \u2013 das ORIGINAL<\/strong> statt. Das Turnier l\u00e4dt alle Padel-Begeisterten zu einem besonderen Wettkampferlebnis in einer der bekanntesten Padelanlagen Wiens ein.<\/p>\n<p>Die Anmeldung ist ab sofort \u00fcber folgenden Link m\u00f6glich: <a href=\"https:\/\/padel-austria.at\/ranked\/tournaments\/9b46e589-1638-4572-860c-9d0df978ae62\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>. Sichert euch euren Platz und seid dabei!<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 1. September 2026 findet im PADELDOME Erdberg in Wien (U3 Erdberg) der Padeldome Breakfast Club \u2013 das ORIGINAL statt. Das Turnier l\u00e4dt alle Padel-Begeisterten zu einem besonderen Wettkampferlebnis in einer der bekanntesten Padelanlagen Wiens ein. Die Anmeldung ist ab sofort \u00fcber folgenden Link m\u00f6glich: Jetzt anmelden. Sichert euch euren Platz und seid dabei!<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277],"class_list":["post-28547","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-09-01","single_start_time":"09:00:00","single_end_date":"2026-09-01","single_end_time":"14:00:00","geschlecht":[],"event_company":[16551],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/padel-austria.at\/ranked\/tournaments\/9b46e589-1638-4572-860c-9d0df978ae62","venue":{"venue_title":"PADELDOME Erdberg","address":"Franzosengraben 2, 1030 Wien (U3 Erdberg)","location":{"address":"Franzosengraben 2, 1030 Wien (U3 Erdberg)","lat":48.1904145792276,"lng":16.4114688164112,"zoom":14,"place_id":"","city":"Wien (U3 Erdberg)","state":"Wien","post_code":1030,"country":"AT"},"postal_code":"1030","city":"Wien (U3 Erdberg)","country":"AT","website":"","contact_person":"","email":"","phone":""},"uuid":"at_9b46e589-1638-4572-860c-9d0df978ae62"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/ecom_event\/28547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/padel_association\/16551"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/media?parent=28547"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/tags?post=28547"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/ecom_event_category?post=28547"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/it\/wp-json\/wp\/v2\/ecom_event_level?post=28547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}