{"id":25528,"date":"2026-03-16T03:09:51","date_gmt":"2026-03-16T03:09:51","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-250-h00-m00-gladius-games-sportmuehle-hilden\/"},"modified":"2026-03-30T02:06:50","modified_gmt":"2026-03-30T02:06:50","slug":"dpv-gps-250-h00-m00-gladius-games-sportmuehle-hilden","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/nl\/padel-toernooien-2\/dpv-gps-250-h00-m00-gladius-games-sportmuehle-hilden\/","title":{"rendered":"GPS 250 H00 \/ M00 &#8211; Gladius Games &#8211; Sportm\u00fchle Hilden"},"content":{"rendered":"<p>Das GPS 250 Turnier der &#8222;Gladius Games&#8220; findet am 29. M\u00e4rz 2026 in der Sportm\u00fchle Hilden statt. Insgesamt 70 Teilnehmer treten in den Klassen GPS 250 H00 und GPS 250 M00 an, mit je maximal 16 beziehungsweise 8 Teams. Der Veranstalter, Christian Tittmann, hat die Teilnahmekosten auf 35 \u20ac pro Person festgelegt. Das Event wird von der deutschen Padel-Vereinigung (DPV) anerkannt. Eine g\u00fcltige DPV-Spielerlizenz ist Voraussetzung. Anmeldeschluss ist der 23. M\u00e4rz, und die Registrierung erfolgt ausschlie\u00dflich als Team.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das GPS 250 Turnier der &#8222;Gladius Games&#8220; findet am 29. M\u00e4rz 2026 in der Sportm\u00fchle Hilden statt. Insgesamt 70 Teilnehmer treten in den Klassen GPS 250 H00 und GPS 250 M00 an, mit je maximal 16 beziehungsweise 8 Teams. Der Veranstalter, Christian Tittmann, hat die Teilnahmekosten auf 35 \u20ac pro Person festgelegt. Das Event wird&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[284],"class_list":["post-25528","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-weltklasse"],"acf":{"cpt_status":"inactive","type":"event","single_start_date":"20260329","single_start_time":"09:00:00","single_end_date":"20260329","single_end_time":"21:00:00","geschlecht":[],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":35,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/62546","venue":{"venue_title":"Sportm\u00fchle Hilden","address":"Berliner Str. 55, 40721 Hilden, Germany","location":{"address":"Berliner Str. 55, 40721 Hilden, Deutschland","lat":51.1696964,"lng":6.944391899999999,"zoom":14,"city":"Hilden","country":"DE","country_short":"DE","post_code":40721},"postal_code":"40721","city":"Hilden","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_62546"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event\/25528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/media?parent=25528"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/tags?post=25528"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_category?post=25528"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_level?post=25528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}