{"id":26907,"date":"2026-07-08T02:03:45","date_gmt":"2026-07-08T02:03:45","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-100-herren-early-afternoon-padelon-gelsenkirchen\/"},"modified":"2026-07-08T02:03:45","modified_gmt":"2026-07-08T02:03:45","slug":"dpv-gps-100-herren-early-afternoon-padelon-gelsenkirchen","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/nl\/padel-toernooien-2\/dpv-gps-100-herren-early-afternoon-padelon-gelsenkirchen\/","title":{"rendered":"GPS 100 Herren &#8211; [EARLY AFTERNOON] &#8211; Padelon Gelsenkirchen"},"content":{"rendered":"<p>Das Paddelturnier &#8222;GPS 100 Herren &#8211; Early Afternoon&#8220; findet im Padelon Gelsenkirchen statt. Hier treten bis zu acht Teams gegeneinander an. Veranstaltet wird das Turnier von Padelon Gelsenkirchen, wobei die Organisation unter anderem von Marcos Valentim Duarte und Lina Vogel geleitet wird. Startschuss ist am 15. Juli 2026 um 13:00 Uhr. F\u00fcr den Wettbewerb fallen pro Person Teilnahmegeb\u00fchren in H\u00f6he von 40 Euro an, die \u00fcber PayPal oder EC-Karte gezahlt werden k\u00f6nnen. Gewinner des Turniers k\u00f6nnen sich auf Sachpreise freuen, die mit Unterst\u00fctzung der Partner des Veranstalters bereitgestellt werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Paddelturnier &#8222;GPS 100 Herren &#8211; Early Afternoon&#8220; findet im Padelon Gelsenkirchen statt. Hier treten bis zu acht Teams gegeneinander an. Veranstaltet wird das Turnier von Padelon Gelsenkirchen, wobei die Organisation unter anderem von Marcos Valentim Duarte und Lina Vogel geleitet wird. Startschuss ist am 15. Juli 2026 um 13:00 Uhr. F\u00fcr den Wettbewerb fallen&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276,277,284],"class_list":["post-26907","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger","ecom_event_level-fortgeschrittene","ecom_event_level-weltklasse"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-07-15","single_start_time":"13:00:00","single_end_date":"2026-07-15","single_end_time":"17:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":40,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/71088","venue":{"venue_title":"Padelon Gelsenkirchen","address":"Zweckeler Str. 55, 45896 Gelsenkirchen, Germany","location":{"address":"Zweckeler Str. 55, 45896 Gelsenkirchen, Germany","lat":51.5831378,"lng":7.0177456,"zoom":14,"place_id":"ChIJWfaxlRbvuEcRnnfgCSIY07U","city":"Gelsenkirchen","state":"","post_code":45896,"country":"DE"},"postal_code":"45896","city":"Gelsenkirchen","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_71088"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event\/26907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/media?parent=26907"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/tags?post=26907"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_category?post=26907"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_level?post=26907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}