{"id":27752,"date":"2026-08-11T20:29:01","date_gmt":"2026-08-11T20:29:01","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/abendturnier-mitte-the-cabrio-hamburg-wandsbek\/"},"modified":"2026-08-11T20:29:01","modified_gmt":"2026-08-11T20:29:01","slug":"abendturnier-mitte-the-cabrio-hamburg-wandsbek","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/nl\/padel-toernooien-2\/abendturnier-mitte-the-cabrio-hamburg-wandsbek\/","title":{"rendered":"Abendturnier \/\/ mitte \u2014 the cabrio \/\/ Hamburg-Wandsbek"},"content":{"rendered":"<p>Am 5. September 2026 findet das <strong>Abendturnier \/\/ mitte \u2014 the cabrio<\/strong> in der Anlage <strong>mitte \u2014 The Cabrio<\/strong> in Hamburg-Wandsbek statt. Padel-Fans d\u00fcrfen sich auf einen sportlichen Abend in einer der angesagten Hamburger Padelanlagen freuen.<\/p>\n<p>Die Anmeldung zum Turnier ist ab sofort online m\u00f6glich. Interessierte k\u00f6nnen sich direkt \u00fcber den offiziellen <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/a02eff4b-e509-4ebc-a81a-69e22daffb4c\" rel=\"nofollow noopener\" target=\"_blank\">Anmeldelink<\/a> registrieren und ihren Platz sichern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 5. September 2026 findet das Abendturnier \/\/ mitte \u2014 the cabrio in der Anlage mitte \u2014 The Cabrio in Hamburg-Wandsbek statt. Padel-Fans d\u00fcrfen sich auf einen sportlichen Abend in einer der angesagten Hamburger Padelanlagen freuen. Die Anmeldung zum Turnier ist ab sofort online m\u00f6glich. Interessierte k\u00f6nnen sich direkt \u00fcber den offiziellen Anmeldelink registrieren und&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[278],"class_list":["post-27752","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-profi"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-09-05","single_start_time":"17:00:00","single_end_date":"2026-09-05","single_end_time":"21:00:00","geschlecht":["Damen"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/a02eff4b-e509-4ebc-a81a-69e22daffb4c","venue":{"venue_title":"mitte \u2014 The Cabrio","address":"Wandsbeker Zollstra\u00dfe 25-29, Hamburg","location":{"address":"Ni Hao, 25-29, Wandsbeker Zollstra\u00dfe, Hinschenfelde, Wandsbek, Hamburg, 22041, Deutschland","lat":53.5752095,"lng":10.0744829,"zoom":14,"place_id":143223170,"city":"Hamburg","state":"","post_code":22041,"country":"DE"},"postal_code":"22041","city":"Hamburg","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_f0b3a5e9-b47f-4ff5-b95f-818af7808d28"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event\/27752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/media?parent=27752"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/tags?post=27752"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_category?post=27752"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/ecom_event_level?post=27752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}