{"id":19645,"date":"2022-11-07T18:22:06","date_gmt":"2022-11-07T18:22:06","guid":{"rendered":"https:\/\/www.padel-test.de\/?page_id=19645"},"modified":"2022-11-08T19:02:07","modified_gmt":"2022-11-08T19:02:07","slug":"organisator-van-padeltoernooien-2","status":"publish","type":"page","link":"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/","title":{"rendered":"Organisator van padeltoernooien"},"content":{"rendered":"\n\n\t[borlabs-cookie id=&#8220;googlemaps&#8220; type=&#8220;content-blocker&#8220;][\/borlabs-cookie]<div class=\"wpgb-facet wpgb-loading wpgb-facet-9\" data-facet=\"9\" data-grid=\"21\"><\/div>\n<h2>\n\t\tPadel Veranstalter\n\t<\/h2>\n\t<div class=\"wpgb-facet wpgb-loading wpgb-facet-11\" data-facet=\"11\" data-grid=\"21\"><\/div>\n\t<!-- Gridbuilder \u1d42\u1d3e Plugin (https:\/\/wpgridbuilder.com) -->\n<div class=\"wp-grid-builder wpgb-grid-21 ecom-grid-padel-organizer\" data-options=\"{&quot;id&quot;:21,&quot;type&quot;:&quot;masonry&quot;,&quot;source&quot;:&quot;post_type&quot;,&quot;loader&quot;:0,&quot;layout&quot;:&quot;vertical&quot;,&quot;reveal&quot;:0,&quot;isMainQuery&quot;:0,&quot;lazyLoad&quot;:1,&quot;cardSizes&quot;:{&quot;9999&quot;:{&quot;columns&quot;:2,&quot;height&quot;:240,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;1200&quot;:{&quot;columns&quot;:2,&quot;height&quot;:240,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;992&quot;:{&quot;columns&quot;:2,&quot;height&quot;:220,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;768&quot;:{&quot;columns&quot;:1,&quot;height&quot;:220,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;576&quot;:{&quot;columns&quot;:1,&quot;height&quot;:200,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;320&quot;:{&quot;columns&quot;:1,&quot;height&quot;:200,&quot;gutter&quot;:16,&quot;ratio&quot;:&quot;1.33333&quot;}},&quot;fitRows&quot;:1,&quot;equalRows&quot;:0,&quot;equalColumns&quot;:1,&quot;fillLastRow&quot;:0,&quot;centerLastRow&quot;:0,&quot;horizontalOrder&quot;:0,&quot;fullWidth&quot;:0,&quot;transitionDelay&quot;:100,&quot;gallerySlideshow&quot;:0,&quot;rowsNumber&quot;:1,&quot;slideAlign&quot;:&quot;left&quot;,&quot;groupCells&quot;:1,&quot;draggable&quot;:1,&quot;initialIndex&quot;:0,&quot;contain&quot;:0,&quot;freeScroll&quot;:0,&quot;freeFriction&quot;:&quot;0.075&quot;,&quot;friction&quot;:&quot;0.285&quot;,&quot;attraction&quot;:&quot;0.025&quot;,&quot;autoPlay&quot;:0,&quot;pageDotAriaLabel&quot;:&quot;Page dot %d&quot;,&quot;isPreview&quot;:false,&quot;isGutenberg&quot;:false,&quot;rightToLeft&quot;:false}\"><div class=\"wpgb-svg-icons\" hidden>\n\t<svg viewBox=\"0 0 120 24\" width=\"0\" height=\"0\">\n\t<defs>\n        <polygon id=\"wpgb-star-svg\" points=\"12 2.5 15.1 8.8 22 9.8 17 14.6 18.2 21.5 12 18.3 5.8 21.5 7 14.6 2 9.8 8.9 8.8\"><\/polygon>\n    <\/defs>\n    <symbol id=\"wpgb-rating-stars-svg\">\n        <use xlink:href=\"#wpgb-star-svg\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"24\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"48\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"72\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"96\"><\/use>\n    <\/symbol>\n<\/svg>\n<\/div>\n<div class=\"wpgb-wrapper\">\n\t<div class=\"wpgb-main\">\n\t<div class=\"wpgb-layout\">\n\t<div class=\"wpgb-viewport\">\n\t\t<div class=\"wpgb-masonry\">\n\t\t\t<article class=\"wpgb-card wpgb-card-30 wpgb-post-17412\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\"><h4 class=\"wpgb-block-1 wpgb-idle-scheme-1\">adidas International Paddle Challenge Madison<\/h4><div class=\"wpgb-block-4 wpgb-idle-scheme-1\">Spanien<\/div><div class=\"wpgb-block-6 wpgb-idle-scheme-1\">\/  Madrid<\/div><div class=\"wpgb-block-2\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"40\" src=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1-136x68.png\" class=\"attachment-80x40 size-80x40\" alt=\"\" style=\"object-fit:contain\" srcset=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1-136x68.png 136w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1-150x75.png 150w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1-18x9.png 18w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1-64x32.png 64w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/int_padelchallenge_e731-1.png 172w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/><\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/adidas-internationale-paddle-challenge-madison\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-30 wpgb-post-17417\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\"><h4 class=\"wpgb-block-1 wpgb-idle-scheme-1\">European Padel Tour<\/h4><div class=\"wpgb-block-4 wpgb-idle-scheme-1\">D\u00e4nemark<\/div><div class=\"wpgb-block-6 wpgb-idle-scheme-1\">\/  Jyderup<\/div><div class=\"wpgb-block-2\"><img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"40\" src=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1-150x135.png\" class=\"attachment-80x40 size-80x40\" alt=\"\" style=\"object-fit:contain\" srcset=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1-150x135.png 150w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1-13x12.png 13w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1-76x68.png 76w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1-64x57.png 64w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/548d5aacb0bbb_d22e-1.png 234w\" sizes=\"auto, (max-width: 44px) 100vw, 44px\" \/><\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/europese-padel-tour\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-30 wpgb-post-17422\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\"><h4 class=\"wpgb-block-1 wpgb-idle-scheme-1\">German Padel Tour<\/h4><div class=\"wpgb-block-4 wpgb-idle-scheme-1\">Deutschland<\/div><div class=\"wpgb-block-6 wpgb-idle-scheme-1\">\/  Bochum<\/div><div class=\"wpgb-block-2\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"40\" src=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1-150x80.png\" class=\"attachment-80x40 size-80x40\" alt=\"\" style=\"object-fit:contain\" srcset=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1-150x80.png 150w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1-18x10.png 18w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1-127x68.png 127w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1-64x34.png 64w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/german_padel_tour_200x107_logo-1.png 200w\" sizes=\"auto, (max-width: 75px) 100vw, 75px\" \/><\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/duitse-padel-tour\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-30 wpgb-post-17400\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\"><h4 class=\"wpgb-block-1 wpgb-idle-scheme-1\">Padel Test<\/h4><div class=\"wpgb-block-4 wpgb-idle-scheme-1\">Deutschland<\/div><div class=\"wpgb-block-6 wpgb-idle-scheme-1\">\/  Rheine<\/div><div class=\"wpgb-block-2\"><img loading=\"lazy\" decoding=\"async\" width=\"54\" height=\"40\" src=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1-150x112.jpg\" class=\"attachment-80x40 size-80x40\" alt=\"\" style=\"object-fit:contain\" srcset=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1-150x112.jpg 150w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1-16x12.jpg 16w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1-91x68.jpg 91w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1-64x48.jpg 64w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/padel_test_160x119_logo_portrait-neu-1.jpg 160w\" sizes=\"auto, (max-width: 54px) 100vw, 54px\" \/><\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/padel-test\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-30 wpgb-post-17406\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\"><h4 class=\"wpgb-block-1 wpgb-idle-scheme-1\">World Padel Tour WPT<\/h4><div class=\"wpgb-block-4 wpgb-idle-scheme-1\">Spanien<\/div><div class=\"wpgb-block-6 wpgb-idle-scheme-1\">\/  Madrid<\/div><div class=\"wpgb-block-2\"><img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"40\" src=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1-150x92.png\" class=\"attachment-80x40 size-80x40\" alt=\"\" style=\"object-fit:contain\" srcset=\"https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1-150x92.png 150w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1-18x12.png 18w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1-111x68.png 111w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1-64x39.png 64w, https:\/\/www.padel-test.de\/wp-content\/uploads\/2022\/09\/wpt_world_padel_tour_200x123_logo-1-1.png 200w\" sizes=\"auto, (max-width: 65px) 100vw, 65px\" \/><\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.padel-test.de\/nl\/organisator-van-padeltoernooien-2\/wereld-padel-tour\/\"><\/a><\/div><\/div><\/article>\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"wpgb-area wpgb-area-bottom-1\">\n\t<div class=\"wpgb-facet wpgb-loading wpgb-facet-2\" data-facet=\"2\" data-grid=\"21\"><\/div><\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-19645","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/pages\/19645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/comments?post=19645"}],"version-history":[{"count":0,"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/pages\/19645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/nl\/wp-json\/wp\/v2\/media?parent=19645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}