{"id":25897,"date":"2026-04-16T02:03:52","date_gmt":"2026-04-16T02:03:52","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-100-herren-racket-republic-bramsche\/"},"modified":"2026-04-26T02:05:26","modified_gmt":"2026-04-26T02:05:26","slug":"dpv-gps-100-maen-racket-republik-bramsche","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/sv\/padel-turneringar-2\/dpv-gps-100-maen-racket-republik-bramsche\/","title":{"rendered":"GPS 100 Herren &#8211; Racket Republic Bramsche"},"content":{"rendered":"<p>Das Paddelturnier &#8222;GPS 100 Herren&#8220; findet in der Racket Republic Bramsche statt. Am 25. April 2026 werden insgesamt 8 Teams gegeneinander antreten. Organisiert wird das Turnier von Michael Vetterick. Die Veranstaltung beginnt um 10 Uhr und endet gegen 16 Uhr. Die Teilnahmegeb\u00fchr betr\u00e4gt 35 Euro pro Person, die vor Ort entweder in bar oder per EC-Karte gezahlt wird. Die Gewinner des Turniers d\u00fcrfen sich \u00fcber Guthaben f\u00fcr zuk\u00fcnftige Platzbuchungen freuen. Jedes Team hat die Chance auf mindestens drei Spiele, da alle Pl\u00e4tze ausgespielt werden. Anmeldungen werden nach dem &#8222;First come, first served&#8220;-Prinzip angenommen, und es m\u00fcssen vollst\u00e4ndige Teams angemeldet werden. Eine g\u00fcltige DPV-Spielerlizenz ist Voraussetzung f\u00fcr die Teilnahme.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Paddelturnier &#8222;GPS 100 Herren&#8220; findet in der Racket Republic Bramsche statt. Am 25. April 2026 werden insgesamt 8 Teams gegeneinander antreten. Organisiert wird das Turnier von Michael Vetterick. Die Veranstaltung beginnt um 10 Uhr und endet gegen 16 Uhr. Die Teilnahmegeb\u00fchr betr\u00e4gt 35 Euro pro Person, die vor Ort entweder in bar oder per&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[284],"class_list":["post-25897","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-weltklasse"],"acf":{"cpt_status":"inactive","type":"event","single_start_date":"20260425","single_start_time":"10:00:00","single_end_date":"20260425","single_end_time":"16:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":35,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/66681","venue":{"venue_title":"Racket Republic Bramsche","address":"V\u00f6rdener Damm 15, 49565 Bramsche, Germany","location":{"address":"V\u00f6rdener Damm 15, 49565 Bramsche, Deutschland","lat":52.4125165,"lng":8.0021117,"zoom":14,"city":"Bramsche","country":"DE","country_short":"DE","post_code":49565},"postal_code":"49565","city":"Bramsche","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_66681"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event\/25897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/media?parent=25897"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/tags?post=25897"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_category?post=25897"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_level?post=25897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}