{"id":26099,"date":"2026-05-03T02:06:44","date_gmt":"2026-05-03T02:06:44","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/dpv-gps-50-herren-early-bird-padelon-gelsenkirchen-4\/"},"modified":"2026-05-03T02:06:44","modified_gmt":"2026-05-03T02:06:44","slug":"dpv-gps-50-herren-early-bird-padelon-gelsenkirchen-4","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/sv\/padel-turneringar-2\/dpv-gps-50-herren-early-bird-padelon-gelsenkirchen-4\/","title":{"rendered":"GPS 50 Herren &#8211; [EARLY BIRD] &#8211; Padelon Gelsenkirchen"},"content":{"rendered":"<p>Das Paddelturnier GPS 50 Herren &#8211; EARLY BIRD wird bei Padelon Gelsenkirchen stattfinden. Es nehmen 12 Spieler teil, was maximal acht Teams ergibt. Der Veranstalter des Turniers ist Padelon Gelsenkirchen, mit Marcos Valentim Duarte als Kontaktperson. Das Turnier l\u00e4uft im KO-System mit Nebenrunde, wodurch jedes Team mindestens zwei Matches spielt. Die Siegerteams erhalten Sachpreise. Die Anmeldung erfolgt als vollst\u00e4ndiges Team, zur Teilnahme ist keine DPV-Lizenz erforderlich. Eine Anmeldung \u00fcber Rankedin oder per E-Mail ist notwendig. Die Teilnahmegeb\u00fchr betr\u00e4gt 40 Euro pro Person und ist vor Ort zu entrichten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Paddelturnier GPS 50 Herren &#8211; EARLY BIRD wird bei Padelon Gelsenkirchen stattfinden. Es nehmen 12 Spieler teil, was maximal acht Teams ergibt. Der Veranstalter des Turniers ist Padelon Gelsenkirchen, mit Marcos Valentim Duarte als Kontaktperson. Das Turnier l\u00e4uft im KO-System mit Nebenrunde, wodurch jedes Team mindestens zwei Matches spielt. Die Siegerteams erhalten Sachpreise. Die&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276],"class_list":["post-26099","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-05-13","single_start_time":"10:00:00","single_end_date":"2026-05-13","single_end_time":"14:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":40,"currency":"EUR","registration_url":"https:\/\/rankedin.com\/de\/join\/tournament\/67797","venue":{"venue_title":"Padelon Gelsenkirchen","address":"Zweckeler Str. 55, 45896 Gelsenkirchen, Germany","location":null,"postal_code":"","city":"","country":false,"website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_67797"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event\/26099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/media?parent=26099"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/tags?post=26099"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_category?post=26099"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_level?post=26099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}