{"id":28672,"date":"2026-09-01T05:19:08","date_gmt":"2026-09-01T05:19:08","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/gps-50-herren-peakz-padel-kleve-2\/"},"modified":"2026-09-01T05:19:08","modified_gmt":"2026-09-01T05:19:08","slug":"gps-50-herren-peakz-padel-kleve-2","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/sv\/padel-turneringar-2\/gps-50-herren-peakz-padel-kleve-2\/","title":{"rendered":"GPS 50 Herren \u2013 Peakz Padel Kleve"},"content":{"rendered":"<p>Am 6. November 2026 findet in der Peakz Padel Kleve in Kleve das <strong>GPS 50 Herren \u2013 Peakz Padel Kleve<\/strong> statt. Das Turnier richtet sich an Herren-Spieler und verspricht einen spannenden Wettkampftag in modernem Ambiente.<\/p>\n<p>Interessierte Spieler k\u00f6nnen sich direkt \u00fcber den offiziellen Anmeldelink des Deutschen Padel Verbands registrieren: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/836ef97f-a13d-45ff-b569-a1005faaff9d\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 6. November 2026 findet in der Peakz Padel Kleve in Kleve das GPS 50 Herren \u2013 Peakz Padel Kleve statt. Das Turnier richtet sich an Herren-Spieler und verspricht einen spannenden Wettkampftag in modernem Ambiente. Interessierte Spieler k\u00f6nnen sich direkt \u00fcber den offiziellen Anmeldelink des Deutschen Padel Verbands registrieren: Jetzt anmelden.<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276],"class_list":["post-28672","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-11-06","single_start_time":"16:00:00","single_end_date":"2026-11-06","single_end_time":"21:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/836ef97f-a13d-45ff-b569-a1005faaff9d","venue":{"venue_title":"Peakz Padel Kleve","address":"Van-den-Bergh-Str. 45, Kleve","location":{"address":"45, Van-den-Bergh-Stra\u00dfe, Kellen, Kleve, Bedburg-Hau, Kreis Kleve, Nordrhein-Westfalen, 47533, Deutschland","lat":51.7901668,"lng":6.1515587,"zoom":14,"place_id":113721445,"city":"Kleve","state":"Nordrhein-Westfalen","post_code":47533,"country":"DE"},"postal_code":"47533","city":"Kleve","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_fe126e4c-25ff-4840-b2b7-b14935259d0b"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event\/28672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/media?parent=28672"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/tags?post=28672"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_category?post=28672"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_level?post=28672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}