{"id":28674,"date":"2026-09-01T05:19:09","date_gmt":"2026-09-01T05:19:09","guid":{"rendered":"https:\/\/www.padel-test.de\/padel-turniere\/star-padel-obernburg\/"},"modified":"2026-09-01T05:19:09","modified_gmt":"2026-09-01T05:19:09","slug":"star-padel-obernburg","status":"publish","type":"ecom_event","link":"https:\/\/www.padel-test.de\/sv\/padel-turneringar-2\/star-padel-obernburg\/","title":{"rendered":"STAR PADEL &#8211; Obernburg"},"content":{"rendered":"<p>Am 31. Oktober 2026 findet das Turnier <strong>STAR PADEL \u2013 Obernburg<\/strong> in der STAR PADEL Anlage in Obernburg am Main statt. Wer sich f\u00fcr den Wettkampf begeistert und sein K\u00f6nnen auf dem Padelfeld unter Beweis stellen m\u00f6chte, ist herzlich willkommen.<\/p>\n<p>Die Anmeldung zum Turnier ist bequem online m\u00f6glich \u2013 einfach den folgenden Link nutzen und einen Platz sichern: <a href=\"https:\/\/portal.dpv-padel.de\/tournaments\/4ff8d557-c012-4dd7-9e08-9532872b6ded\" rel=\"nofollow noopener\" target=\"_blank\">Jetzt anmelden<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 31. Oktober 2026 findet das Turnier STAR PADEL \u2013 Obernburg in der STAR PADEL Anlage in Obernburg am Main statt. Wer sich f\u00fcr den Wettkampf begeistert und sein K\u00f6nnen auf dem Padelfeld unter Beweis stellen m\u00f6chte, ist herzlich willkommen. Die Anmeldung zum Turnier ist bequem online m\u00f6glich \u2013 einfach den folgenden Link nutzen und&hellip;<\/p>","protected":false},"featured_media":0,"template":"","tags":[199],"ecom_event_category":[275],"ecom_event_level":[276],"class_list":["post-28674","ecom_event","type-ecom_event","status-publish","hentry","tag-padel-turnier","ecom_event_category-turnier","ecom_event_level-anfaenger"],"acf":{"cpt_status":"active","type":"event","single_start_date":"2026-10-31","single_start_time":"08:00:00","single_end_date":"2026-10-31","single_end_time":"12:00:00","geschlecht":["Herren"],"event_company":[16586],"organizer_notice":"","is_free":"kostenpflichtig","price":0,"currency":"EUR","registration_url":"https:\/\/portal.dpv-padel.de\/tournaments\/4ff8d557-c012-4dd7-9e08-9532872b6ded","venue":{"venue_title":"STAR PADEL Obernburg","address":"An den Tennispl\u00e4tzen, Obernburg","location":{"address":"An den Tennispl\u00e4tzen, Obernburg, Obernburg am Main, Landkreis Miltenberg, Bayern, 63785, Deutschland","lat":49.8409636,"lng":9.1353207,"zoom":14,"place_id":125693302,"city":"Obernburg am Main","state":"Bayern","post_code":63785,"country":"DE"},"postal_code":"63785","city":"Obernburg am Main","country":"DE","website":"","contact_person":"","email":"","phone":""},"uuid":"dpv_eade60c1-62c9-4836-88f1-eb116a84d5ab"},"_links":{"self":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event\/28674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event"}],"about":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/types\/ecom_event"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/padel_association\/16586"}],"wp:attachment":[{"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/media?parent=28674"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/tags?post=28674"},{"taxonomy":"ecom_event_category","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_category?post=28674"},{"taxonomy":"ecom_event_level","embeddable":true,"href":"https:\/\/www.padel-test.de\/sv\/wp-json\/wp\/v2\/ecom_event_level?post=28674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}